{"id":316,"date":"2024-10-18T21:30:52","date_gmt":"2024-10-18T21:30:52","guid":{"rendered":"https:\/\/indismile.com\/implantes\/"},"modified":"2024-12-02T18:48:24","modified_gmt":"2024-12-02T18:48:24","slug":"implants","status":"publish","type":"page","link":"https:\/\/indismile.com\/en\/implants\/","title":{"rendered":"Implants"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_400009759\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\t<div class=\"ux-shape-divider ux-shape-divider--bottom ux-shape-divider--style-triangle-opacity ux-shape-divider--to-front\">\n\t\t<svg viewBox=\"0 0 1000 100\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n\t<path class=\"ux-shape-fill\" d=\"M1025 100H-25L500 24L1025 100Z\"\/>\n\t<path class=\"ux-shape-fill\" opacity=\"0.3\" d=\"M1025 100H-25L500 0L1025 100Z\"\/>\n<\/svg>\n\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse row-full-width align-middle align-center\"  id=\"row-1955711669\">\n\n\n\t<div id=\"col-1134680226\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-235582982\" class=\"col hide-for-medium medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-256118446\" class=\"text\">\n\t\t\n\n<h1><span style=\"color: #7bafde;\"><b>Implants<\/b><\/span><\/h1>\n\t\t\n<style>\n#text-256118446 {\n  font-size: 3rem;\n  text-align: left;\n  color: #0066b3;\n}\n#text-256118446 > * {\n  color: #0066b3;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"#contact\" class=\"button primary is-large lowercase\" style=\"border-radius:2px;padding:0px 50px 0px 50px;\">\n\t\t<span>Contact<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-235582982 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1129514965\" class=\"col show-for-medium medium-5 small-12 large-5\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-330554931\" class=\"text\">\n\t\t\n\n<h1><span style=\"color: #7bafde;\"><b>Implants<\/b><\/span><\/h1>\n\t\t\n<style>\n#text-330554931 {\n  font-size: 2rem;\n  text-align: center;\n  color: #0066b3;\n}\n#text-330554931 > * {\n  color: #0066b3;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"http:\/\/indismile\/contacto\" class=\"button primary is-larger lowercase\" style=\"border-radius:2px;padding:0px 50px 0px 50px;\">\n\t\t<span>Contact<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1129514965 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1431001201\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-right\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1409254691\">\n\t\t\t\t\t\t<div data-animate=\"fadeInDown\">\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2807\" height=\"1760\" src=\"https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia.png 2807w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-300x188.png 300w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-1024x642.png 1024w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-768x482.png 768w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-1536x963.png 1536w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-2048x1284.png 2048w\" sizes=\"auto, (max-width: 2807px) 100vw, 2807px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_1409254691 {\n  width: 100%;\n}\n@media (min-width:550px) {\n  #image_1409254691 {\n    width: 100%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1431001201 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -50px 0px;\n}\n@media (min-width:550px) {\n  #col-1431001201 > .col-inner {\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_400009759 {\n  padding-top: 50px;\n  padding-bottom: 50px;\n  background-color: #eff8fb;\n}\n#section_400009759 .ux-shape-divider--bottom svg {\n  height: 50px;\n  --divider-width: 100%;\n}\n@media (min-width:550px) {\n  #section_400009759 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n  #section_400009759 .ux-shape-divider--bottom svg {\n    height: 150px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_130713081\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1924\" height=\"1361\" src=\"https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/FONDO-2-Assets.png\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-middle align-center position-relative\" style=\"max-width:90%\" id=\"row-94994831\">\n\n\n\t<div id=\"col-2144805167\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"ux-lottie-869385287\" class=\"ux-lottie\">\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/lottie.host\\\/7e1cc13e-5909-49de-8b79-f48ec31b5eae\\\/A5DXvrL7uC.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-869385287&quot;}\"><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-869385287 {\n  width: 50%;\n  height: 50%;\n}\n@media (min-width:550px) {\n  #ux-lottie-869385287 {\n    width: 100%;\n    height: 300px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2144805167 > .col-inner {\n  padding: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-416326368\" class=\"col medium-8 small-12 large-8\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2209741314\" class=\"text\">\n\t\t\n\n<p class=\"lead\">At our clinic, we treat gum diseases through periodontics and replace lost teeth with dental implants using implantology. With a comprehensive approach, our specialists ensure safe and effective care for your oral health.<\/p>\n\t\t\n<style>\n#text-2209741314 {\n  font-size: 0.9rem;\n  text-align: center;\n  color: #76abdf;\n}\n#text-2209741314 > * {\n  color: #76abdf;\n}\n@media (min-width:550px) {\n  #text-2209741314 {\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-416326368 > .col-inner {\n  padding: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-329734748\" class=\"col medium-8 small-12 large-8\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-884771115\" class=\"text\">\n\t\t\n\n<h2>Discover Our Periodontics and Implantology Services<\/h2>\n<hr style=\"border: 1px solid #6ac9c7; opacity: 100%;\" \/>\n\t\t\n<style>\n#text-884771115 {\n  font-size: 1.25rem;\n  text-align: center;\n  color: #0061b3;\n}\n#text-884771115 > * {\n  color: #0061b3;\n}\n@media (min-width:550px) {\n  #text-884771115 {\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-173051667\">\n\n\n\t<div id=\"col-738401152\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2999277892\" class=\"text hide-for-medium\">\n\t\t\n\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Deep cleanings<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Access surgery<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Bone and gum grafting<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Gingivectomy \/ Gingivoplasty<\/span><\/li>\n<\/ul>\n\t\t\n<style>\n#text-2999277892 {\n  font-size: 1.25rem;\n  text-align: center;\n  color: rgb(0, 102, 179);\n}\n#text-2999277892 > * {\n  color: rgb(0, 102, 179);\n}\n@media (min-width:550px) {\n  #text-2999277892 {\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-579476570\" class=\"text show-for-medium\">\n\t\t\n\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Deep cleanings<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Access surgery<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Bone and gum grafting<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Gingivectomy \/ Gingivoplasty<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Implants<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Hybrid prostheses \/ All-on-4<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Pre-prosthetic surgery (crown lengthening)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Evaluation appointment<\/span><\/li>\n<\/ul>\n\t\t\n<style>\n#text-579476570 {\n  font-size: 1.2rem;\n  text-align: left;\n  color: rgb(0, 102, 179);\n}\n#text-579476570 > * {\n  color: rgb(0, 102, 179);\n}\n@media (min-width:550px) {\n  #text-579476570 {\n    font-size: 1.25rem;\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1636531717\" class=\"col hide-for-medium medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1837160446\" class=\"text\">\n\t\t\n\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Implants<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Hybrid prostheses \/ All-on-4<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Pre-prosthetic surgery (crown lengthening)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Evaluation appointment<\/span><\/li>\n<\/ul>\n\t\t\n<style>\n#text-1837160446 {\n  font-size: 1.25rem;\n  text-align: center;\n  color: rgb(0, 102, 179);\n}\n#text-1837160446 > * {\n  color: rgb(0, 102, 179);\n}\n@media (min-width:550px) {\n  #text-1837160446 {\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-329734748 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-592749838\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1233312993\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"563\" height=\"458\" src=\"https:\/\/indismile.com\/wp-content\/uploads\/2024\/11\/ASSETS-MANO-1.2-1-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/indismile.com\/wp-content\/uploads\/2024\/11\/ASSETS-MANO-1.2-1-1.png 563w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/11\/ASSETS-MANO-1.2-1-1-300x244.png 300w\" sizes=\"auto, (max-width: 563px) 100vw, 563px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1233312993 {\n  width: 75%;\n}\n@media (min-width:550px) {\n  #image_1233312993 {\n    width: 70%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-592749838 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: -50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-600252157\" class=\"col retenedor-position medium-4 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-right\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1871437232\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1559\" height=\"1470\" src=\"https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-1.png 1559w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-1-300x283.png 300w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-1-1024x966.png 1024w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-1-768x724.png 768w, https:\/\/indismile.com\/wp-content\/uploads\/2024\/10\/Periodoncia-1-1536x1448.png 1536w\" sizes=\"auto, (max-width: 1559px) 100vw, 1559px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1871437232 {\n  width: 80%;\n}\n@media (min-width:550px) {\n  #image_1871437232 {\n    width: 70%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n  <div class=\"banner has-hover\" id=\"banner-323493163\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-836709703\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                     <div data-animate=\"fadeInUp\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div id=\"text-746004731\" class=\"text hide-for-medium\">\n\t\t\n\n<h3><strong>Schedule your appointment: +506 8585-5959<\/strong><\/h3>\n\t\t\n<style>\n#text-746004731 {\n  font-size: 1.25rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1708300605\" class=\"text show-for-medium\">\n\t\t\n\n<h3><strong>Schedule your appointment:<br \/><\/strong><\/h3>\n<h3><strong>+506 8585-5959<\/strong><\/h3>\n\t\t\n<style>\n#text-1708300605 {\n  font-size: 0.75rem;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-1708300605 {\n    font-size: 1.25rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-836709703 {\n  width: 100%;\n}\n#text-box-836709703 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-323493163 {\n  padding-top: 100px;\n  background-color: #6ac9c7;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_130713081 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_295791021\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #contact\" data-bullet=\"false\" data-link=\"#contact\" data-title=\"Change this\"><a name=\"contact\"><\/a><\/span>\n\n<div class=\"row row-collapse\"  id=\"row-413687694\">\n\n\n\t<div id=\"col-1304317848\" class=\"col small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-364844401\" class=\"text\">\n\t\t\n\n<h2>What service are you interested in?<\/h2>\n<p class=\"lead\"><span style=\"color: #83b4e0; font-size: 20.8px;\">Fill out the following form, and we will contact you shortly.<\/span><\/p>\n\t\t\n<style>\n#text-364844401 {\n  font-size: 1.25rem;\n  text-align: center;\n  color: #0066b3;\n}\n#text-364844401 > * {\n  color: #0066b3;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1304317848 > .col-inner {\n  padding: 0px 10px 0px 10px;\n  margin: 40px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-198998938\" class=\"col small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f313-o1\" lang=\"es-CR\" dir=\"ltr\" data-wpcf7-id=\"313\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/316#wpcf7-f313-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"313\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.2\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_CR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f313-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<!-- Contenedor principal del formulario -->\n<div class=\"contact-form-row\">\n\t<div class=\"contact-form-half-width contact-form-padding-right\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required contact-form-custom-input\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"contact-form-half-width\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email contact-form-custom-input\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"contact-form-column-centered contact-form-margin-bottom\" style=\"padding: 25px 0;\">\n\t<p><label class=\"blue-label\" class=\"contact-form-bold-text contact-form-margin-bottom-small\">Choose your services of interest*<\/label>\n\t<\/p>\n \n <!-- Contenedor Flex para las 3 columnas de checkboxes -->\n\t<div class=\"contact-form-flex-container contact-form-content-width\">\n\t\t<div class=\"custom-text-center\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"servicios\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"servicios[]\" value=\"General Dentistry\" \/><span class=\"wpcf7-list-item-label\">General Dentistry<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"servicios[]\" value=\"Evaluation Appointment Only in Pediatric Dentistry\" \/><span class=\"wpcf7-list-item-label\">Evaluation Appointment Only in Pediatric Dentistry<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"servicios[]\" value=\"Orthodontics\" \/><span class=\"wpcf7-list-item-label\">Orthodontics<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"servicios[]\" value=\"Occlusion\" \/><span class=\"wpcf7-list-item-label\">Occlusion<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"servicios[]\" value=\"Oral Surgery\" \/><span class=\"wpcf7-list-item-label\">Oral Surgery<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"servicios[]\" value=\"Implants\" \/><span class=\"wpcf7-list-item-label\">Implants<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"servicios[]\" value=\"Aesthetics\" \/><span class=\"wpcf7-list-item-label\">Aesthetics<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"servicios[]\" value=\"Endodontics\" \/><span class=\"wpcf7-list-item-label\">Endodontics<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"contact-form-row\" style=\"padding-bottom: 25px;\">\n\t<div class=\"contact-form-half-width contact-form-padding-right\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"num-telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel contact-form-custom-input\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"tel\" name=\"num-telefono\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea contact-form-custom-textarea\" aria-invalid=\"false\" placeholder=\"Write your question here (optional)\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<div class=\"contact-form-column contact-form-margin-top contact-form-btn-centrado\">\n\t<p><small class=\"contact-form-margin-bottom-small blue-label\" style=\"font-size:14px;padding-right:20px;\">*Required fields<\/small>\n\t<\/p>\n<\/div>\n<div class=\"contact-form-column contact-form-margin-top contact-form-btn-centrado\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-198998938 > .col-inner {\n  padding: 0px 20px 0px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_295791021 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_295791021 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-316","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/indismile.com\/en\/wp-json\/wp\/v2\/pages\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indismile.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/indismile.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/indismile.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indismile.com\/en\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":0,"href":"https:\/\/indismile.com\/en\/wp-json\/wp\/v2\/pages\/316\/revisions"}],"wp:attachment":[{"href":"https:\/\/indismile.com\/en\/wp-json\/wp\/v2\/media?parent=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}